{"id":12691,"date":"2026-05-11T12:19:38","date_gmt":"2026-05-11T12:19:38","guid":{"rendered":"https:\/\/pspv-psoevalencia.org\/2026\/05\/11\/el-pspv-recolza-la-vaga-educativa-i-exigeix-al-consell-que-negocie-amb-el-professorat\/"},"modified":"2026-05-11T12:20:26","modified_gmt":"2026-05-11T12:20:26","slug":"el-pspv-recolza-la-vaga-educativa-i-exigeix-al-consell-que-negocie-amb-el-professorat","status":"publish","type":"post","link":"https:\/\/pspv-psoevalencia.org\/va\/2026\/05\/11\/el-pspv-recolza-la-vaga-educativa-i-exigeix-al-consell-que-negocie-amb-el-professorat\/","title":{"rendered":"El PSPV recolza la vaga educativa i exigeix al Consell que negocie amb el professorat"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li class=\"has-vivid-red-color has-text-color has-link-color has-medium-font-size wp-elements-4c66597acdaddd46dacf3ef2cbeb9366\">Dolors L\u00f3pez destaca el suport massiu de les fam\u00edlies en la manifestaci\u00f3 que ha recorregut els carrers de Val\u00e8ncia<\/li>\n<\/ul>\n\n<p><strong>(Val\u00e8ncia 11\/5\/2026) El Grup Municipal Socialista a l&#8217;Ajuntament de Val\u00e8ncia ha mostrat hui el seu suport a la vaga educativa convocada en defensa de l&#8217;ensenyament p\u00fablic i ha exigit al Govern valenci\u00e0 del Partit Popular que \u00f2briga un proc\u00e9s de negociaci\u00f3 real amb el professorat per a frenar la deterioraci\u00f3 del sistema educatiu p\u00fablic.<\/strong><\/p>\n\n<p>La regidora socialista Dolors L\u00f3pez ha assenyalat que \u201cel grup socialista municipal dona suport a la vaga del professorat en defensa de l&#8217;educaci\u00f3 p\u00fablica i exigeix la negociaci\u00f3 del Govern Popular amb els professors que han dit ja basta a una situaci\u00f3 insostenible de deterioraci\u00f3 de l&#8217;ensenyament p\u00fablic\u201d.<\/p>\n\n<p>L\u00f3pez ha destacat, a m\u00e9s, l&#8217;ampli seguiment de la mobilitzaci\u00f3 a la ciutat de Val\u00e8ncia i la implicaci\u00f3 de tota la comunitat educativa. \u201cEl suport de la comunitat educativa est\u00e0 sent massiu a la ciutat de Val\u00e8ncia i milers de fam\u00edlies estan acompanyant al professorat en la manifestaci\u00f3 que ha arrancat des de la pla\u00e7a de Sant Agust\u00ed\u201d, ha afirmat.<\/p>\n\n<p>En aquest sentit, l&#8217;edil socialista ha insistit que la protesta respon al malestar acumulat per les retallades, la falta de recursos i l&#8217;abs\u00e8ncia de di\u00e0leg per part del Consell. \u201cL&#8217;\u00e8xit \u00e9s rotund perqu\u00e8 \u00e9s una vaga necess\u00e0ria i justa\u201d, ha concl\u00f2s.&#13;\n&#13;\nDes del Grup Socialista han reclamat a l&#8217;Executiu auton\u00f2mic que abandone la confrontaci\u00f3 amb la comunitat educativa i atenga les reivindicacions del professorat per a garantir una educaci\u00f3 p\u00fablica de qualitat, amb m\u00e9s recursos, estabilitat i condicions dignes per a docents i alumnat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(Val\u00e8ncia 11\/5\/2026) El Grup Municipal Socialista a l&#8217;Ajuntament de Val\u00e8ncia ha mostrat hui el seu suport a la vaga educativa convocada en defensa de l&#8217;ensenyament p\u00fablic i ha exigit al Govern valenci\u00e0 del Partit Popular que \u00f2briga un proc\u00e9s de negociaci\u00f3 real amb el professorat per a frenar la deterioraci\u00f3 del sistema educatiu p\u00fablic. La [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12687,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[47,21],"tags":[50,49],"class_list":["post-12691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nota-de-prensa-va","category-noticia-va","tag-pspv-psoe-va","tag-socialistes"],"acf":[],"_links":{"self":[{"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/posts\/12691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/comments?post=12691"}],"version-history":[{"count":1,"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/posts\/12691\/revisions"}],"predecessor-version":[{"id":12692,"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/posts\/12691\/revisions\/12692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/media\/12687"}],"wp:attachment":[{"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/media?parent=12691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/categories?post=12691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pspv-psoevalencia.org\/va\/wp-json\/wp\/v2\/tags?post=12691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}